{"id":89,"date":"2020-07-23T10:52:19","date_gmt":"2020-07-23T08:52:19","guid":{"rendered":"http:\/\/www.fondazionemorra.org\/?post_type=archivi&#038;p=89"},"modified":"2022-02-07T16:00:51","modified_gmt":"2022-02-07T15:00:51","slug":"nanni-balestrini","status":"publish","type":"archivi","link":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/","title":{"rendered":"Nanni Balestrini"},"content":{"rendered":"<h3>Biografia<\/h3>\n<p style=\"text-align: justify;\">Nanni Balestrini nasce a Milano nel 1935. Oltre ad essere poeta, \u00e8 narratore, artista visivo, autore teatrale. \u00c8 uno sperimentatore delle connessioni che legano parole, testi e immagini. Con Pagliarani, Giuliani, Sanguineti e Porta entra a far parte dell&#8217;antologia dei I Novissimi (1961), che \u00e8 un po\u2019 il preludio della neoavanguardia e del Gruppo \u201963, di cui naturalmente Balestrini ha fatto parte. Partecipa alla nascita di importanti riviste letterarie, come \u201cIl Verri\u201d, diretta da Luciano Anceschi, \u201cQuindici\u201d o \u201cAlfabeta\u201d. Sin dall&#8217;inizio \u00e8 affascinato dalle potenzialit\u00e0 espressive del linguaggio, che dissociato dal suo valore semantico diviene l\u2019oggetto della poesia. Ricombinando frammenti linguistici preesistenti, brani di realt\u00e0 prelevati da film, libri e da ogni sorta di medium, Balestrini crea un non linguaggio, il grado zero della significazione, per dare la possibilit\u00e0 al pubblico di generare il proprio. Tra le sue opere di poesia si ricordano Come si agisce (1963), Le ballate della signorina Richmond (1977), Blackout (1981), Caosmogona (2010). Balestrini distrugge e riconfigura i linguaggi, per riprodurre il cortocircuito che avviene tra dinamicit\u00e0 esterna, corpo mobile e pensiero in movimento. La sua vasta produzione comprende poesie sperimentali (\u00e8 stato il primo autore ad usare il computer per comporre una poesia) e romanzi impegnati politicamente riguardanti le lotte del movimento degli anni settanta come Vogliamo tutto (1971), un romanzo-cronaca sui moti operai della Fiat di Torino del 1969, scritto in presa diretta aprendo il microfono del registratore durante le riunioni, le assemblee e le manifestazioni del movimento operaio. Narratore epico, Balestrini racconta altre storie nelle storie, spesso partendo da un sistematico riuso di fonti scritte, senza alcuna discriminazione di provenienza. Il Tristano (2007) \u00e8 un romanzo multiplo, stampato in 2500 copie ognuna diversa dall&#8217;altra secondo le regole dell\u2019ars combinatoria, un remix di frasi preesistenti estratte da atlanti, giornali, romanzi rosa e guide turistiche rimescolate in modo da ottenere un testo narrativo. La dinamicit\u00e0 e l\u2019unicit\u00e0 diversificate emergono con particolare forza nel suo film Tristanoil, presentato a Documenta 13 nel 2012 come il film pi\u00f9 lungo del mondo perch\u00e9 virtualmente di durata infinita. Nel 2010 ha contribuito al lancio della rivista \u201cAlfabeta2\u201d. Parallelamente alla produzione letteraria ha sviluppato una intensa ricerca in campo visivo, documentata nella monografia Con gli occhi del linguaggio (2006).\u00a0 Ha partecipato a numerose mostre in Italia e all&#8217;estero, nel 1993 alla Biennale di Venezia, in seguito a Palazzo Grassi sempre a Venezia e ancora al Centro per l&#8217;arte contemporanea Luigi Pecci di Prato; e con personali alla Galleria Mazzoli di Modena, al MACRO (Museo d\u2019arte contemporanea di Roma), alla Fondazione Morra di Napoli, alla Fondazione Mudimae alla Fondazione Marconi di Milano, al Museion di Bolzano, al Museo Novecento di Firenze.<\/p>\n","protected":false},"featured_media":437,"template":"","class_list":["post-89","archivi","type-archivi","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nanni Balestrini - Fondazione Morra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanni Balestrini - Fondazione Morra\" \/>\n<meta property=\"og:description\" content=\"Biografia Nanni Balestrini nasce a Milano nel 1935. Oltre ad essere poeta, \u00e8 narratore, artista visivo, autore teatrale. \u00c8 uno sperimentatore delle connessioni che legano parole, testi e immagini. Con... Read more &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Morra\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-07T15:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/08\/2_Nanni_Balestrini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/\",\"name\":\"Nanni Balestrini - Fondazione Morra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/2_Nanni_Balestrini.jpg\",\"datePublished\":\"2020-07-23T08:52:19+00:00\",\"dateModified\":\"2022-02-07T15:00:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/2_Nanni_Balestrini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/2_Nanni_Balestrini.jpg\",\"width\":700,\"height\":465,\"caption\":\"Nanni Balestrini, Cosa guardi Cosa vuoi vedere, 2009, Fondazione Morra, Napoli Foto Fabio Donato \u00a9 Fondazione Morra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/nanni-balestrini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artisti\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/archivi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nanni Balestrini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"name\":\"Fondazione Morra\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\",\"name\":\"Fondazione Morra\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"width\":106,\"height\":114,\"caption\":\"Fondazione Morra\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nanni Balestrini - Fondazione Morra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/","og_locale":"it_IT","og_type":"article","og_title":"Nanni Balestrini - Fondazione Morra","og_description":"Biografia Nanni Balestrini nasce a Milano nel 1935. Oltre ad essere poeta, \u00e8 narratore, artista visivo, autore teatrale. \u00c8 uno sperimentatore delle connessioni che legano parole, testi e immagini. Con... Read more &raquo;","og_url":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/","og_site_name":"Fondazione Morra","article_modified_time":"2022-02-07T15:00:51+00:00","og_image":[{"width":700,"height":465,"url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/08\/2_Nanni_Balestrini.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/","url":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/","name":"Nanni Balestrini - Fondazione Morra","isPartOf":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/08\/2_Nanni_Balestrini.jpg","datePublished":"2020-07-23T08:52:19+00:00","dateModified":"2022-02-07T15:00:51+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/#primaryimage","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/08\/2_Nanni_Balestrini.jpg","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/08\/2_Nanni_Balestrini.jpg","width":700,"height":465,"caption":"Nanni Balestrini, Cosa guardi Cosa vuoi vedere, 2009, Fondazione Morra, Napoli Foto Fabio Donato \u00a9 Fondazione Morra"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionemorra.org\/it\/archivi\/nanni-balestrini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionemorra.org\/it\/"},{"@type":"ListItem","position":2,"name":"Artisti","item":"https:\/\/www.fondazionemorra.org\/it\/archivi\/"},{"@type":"ListItem","position":3,"name":"Nanni Balestrini"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionemorra.org\/it\/#website","url":"https:\/\/www.fondazionemorra.org\/it\/","name":"Fondazione Morra","description":"","publisher":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionemorra.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fondazionemorra.org\/it\/#organization","name":"Fondazione Morra","url":"https:\/\/www.fondazionemorra.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","width":106,"height":114,"caption":"Fondazione Morra"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/archivi\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/archivi"}],"about":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/types\/archivi"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media\/437"}],"wp:attachment":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media?parent=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}