{"id":2666,"date":"2020-11-17T12:12:05","date_gmt":"2020-11-17T11:12:05","guid":{"rendered":"http:\/\/www.fondazionemorra.org\/?post_type=tribe_events&#038;p=2666"},"modified":"2021-04-08T11:50:40","modified_gmt":"2021-04-08T09:50:40","slug":"la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli","status":"publish","type":"tribe_events","link":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/","title":{"rendered":"LA ROSA DEI 20 \/ PROJECTLAB Artisti &#038; Studenti dell\u2019Accademia di Belle Arti a Napoli"},"content":{"rendered":"<p><strong>24 novembre 2017 &#8211; 6 gennaio 2018<\/strong><br \/>\nOPENING 24 NOVEMBRE ORE 19:00<br \/>\n<strong>Biblioteca del Museo Hermann Nitsch<\/strong><br \/>\nVico Lungo Pontecorvo 29\/d, Napoli<\/p>\n<p>A cura di Guglielmo Gigliotti e Loredana Troise<\/p>\n<p style=\"text-align: justify;\"><strong>Artisti invitati<\/strong>:<br \/>\nMarisa Albanese, Angelo Casciello, Carolina Ciuccio, Libero De Cunzo, Maurizio Elettrico, Sergio Fermariello, Lucia Gangheri, Christian Leperino, Roberto Marchese, Lello Masucci, Domenico Mennillo, Enza Monetti, Aulo Pedicini, Gianni Pisani, Carmine Rezzuti, Rosy Rox, Mimma Russo, Quintino Scolavino, Marianna Troise, Marco Zezza.<\/p>\n<p style=\"text-align: justify;\"><strong>La mostra La rosa dei 20 \/ projectlab Artisti &amp; Studenti dell\u2019Accademia di Belle Arti a Napoli<\/strong>, che si terr\u00e0 presso il prestigioso <strong>Museo Hermann Nitsch<\/strong> (sale della Biblioteca), \u00e8 il punto d\u2019arrivo di un\u2019indagine sulla percezione e il senso dell\u2019arte contemporanea, realizzata tramite la messa a punto di venti laboratori in cui venti artisti napoletani, diversi per biografie, stili e sensibilit\u00e0, accettando con disponibilit\u00e0 e amicizia l\u2019invito dei curatori, hanno interagito con gli allievi dell\u2019Accademia di Belle Arti di Napoli, condividendo visioni, passioni ed esperienze. Condotto nell\u2019ambito della cattedra di <strong>Storia dell&#8217;Arte Contemporanea<\/strong> del prof. <strong>Guglielmo Gigliotti<\/strong> di cui <strong>Loredana Troise<\/strong> \u00e8 cultrice e lungo l&#8217;Anno Accademico 2016-17, il progetto (disposto, diretto e seguito in tutte le sue molteplici fasi dai curatori) si \u00e8 rivelato, oltre che una preziosa opportunit\u00e0, per l\u2019intreccio di inedite esperienze e collaborazioni, anche un modello relazionale armonico, in progress, inteso come bisogno formativo e prospettiva etica ineludibile per chi si orienta all\u2019apprendimento in settori come quello delle arti. La partecipazione al farsi dell&#8217;arte sperimentata nei workshop, si \u00e8 infine tradotta in una interessante mostra, composta da 20 opere create dagli artisti (dipinti, sculture, fotografie, installazioni e video) che, coniugando pensiero ed eleganza compositiva, hanno interpretato le rotte e le tendenze dell\u2019arte d\u2019oggi: \u201cla rappresentazione grafica delle direzioni di derivazione dei venti, al di l\u00e0 del gioco verbale riferito al numero degli artisti partecipanti, si configura &#8211; per dirla con i curatori &#8211; una buona allegoria della vita del contemporaneo a Napoli, mossa, tra bonacce e tempeste, da direttrici energetiche multiple\u201d.<\/p>\n<p style=\"text-align: justify;\">In mostra, anche i numerosi storyboard elaborati dai corsisti, collegati idealmente alle trame delle opere, a richiamare il dialogo e la sintonia fra le parti: un approccio fondamentale che va sempre preservato e incrementato sebbene in nuove forme come preziosa risorsa intellettuale, utile a rispondere alle sfide del presente.<\/p>\n<p style=\"text-align: justify;\">Per l\u2019occasione, sar\u00e0 pubblicato dalla casa editrice <strong>arte&#8217;m<\/strong> &#8211; un catalogo\u00a0con i testi di <strong>Giuseppe Gaeta<\/strong>, <strong>Giuseppe Morra<\/strong>, <strong>Loredana Troise<\/strong>, <strong>Guglielmo Gigliotti<\/strong>.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2666 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/01-la-rosa-dei20-museo-hermann-nitsch-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"765\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/01-la-rosa-dei20-Museo-Hermann-Nitsch-1-1024x765.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-1-2667\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/01-la-rosa-dei20-Museo-Hermann-Nitsch-1-1024x765.jpg 1024w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/01-la-rosa-dei20-Museo-Hermann-Nitsch-1-300x224.jpg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/01-la-rosa-dei20-Museo-Hermann-Nitsch-1-768x573.jpg 768w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/01-la-rosa-dei20-Museo-Hermann-Nitsch-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2667'>\n\t\t\t\tLa Rosa dei 20 &#8211; Artisti&#038;Studenti dell&#8217;Accademia di Belle Arti di Napoli, Museo Hermann Nitsch, Napoli 2017\nCourtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/02-la-rosa-dei20-museo-hermann-nitsch\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/02-la-rosa-dei20-Museo-Hermann-Nitsch-1024x575.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-1-2669\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/02-la-rosa-dei20-Museo-Hermann-Nitsch-1024x575.jpg 1024w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/02-la-rosa-dei20-Museo-Hermann-Nitsch-300x169.jpg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/02-la-rosa-dei20-Museo-Hermann-Nitsch-768x431.jpg 768w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/02-la-rosa-dei20-Museo-Hermann-Nitsch.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2669'>\n\t\t\t\tLa Rosa dei 20 &#8211; Artisti&#038;Studenti dell&#8217;Accademia di Belle Arti di Napoli, Museo Hermann Nitsch, Napoli 2017 Courtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/03-la-rosa-dei20-museo-hermann-nitsch\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/03-la-rosa-dei20-Museo-Hermann-Nitsch-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-1-2671\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/03-la-rosa-dei20-Museo-Hermann-Nitsch-1024x768.jpg 1024w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/03-la-rosa-dei20-Museo-Hermann-Nitsch-300x225.jpg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/03-la-rosa-dei20-Museo-Hermann-Nitsch-768x576.jpg 768w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/03-la-rosa-dei20-Museo-Hermann-Nitsch.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2671'>\n\t\t\t\tLa Rosa dei 20 &#8211; Artisti&#038;Studenti dell&#8217;Accademia di Belle Arti di Napoli, Museo Hermann Nitsch, Napoli 2017 Courtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/04-la-rosa-dei20-museo-hermann-nitsch\/'><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/04-la-rosa-dei20-Museo-Hermann-Nitsch-576x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-1-2673\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/04-la-rosa-dei20-Museo-Hermann-Nitsch-576x1024.jpg 576w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/04-la-rosa-dei20-Museo-Hermann-Nitsch-169x300.jpg 169w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/04-la-rosa-dei20-Museo-Hermann-Nitsch.jpg 675w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2673'>\n\t\t\t\tLa Rosa dei 20 &#8211; Artisti&#038;Studenti dell&#8217;Accademia di Belle Arti di Napoli, Museo Hermann Nitsch, Napoli 2017 Courtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>24 novembre 2017 &#8211; 6 gennaio 2018 OPENING 24 NOVEMBRE ORE 19:00 Biblioteca del Museo Hermann Nitsch Vico Lungo Pontecorvo 29\/d, Napoli A cura di Guglielmo Gigliotti e Loredana Troise<a class=\"excerpt-read-more\" href=\"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/\" title=\"ReadLA ROSA DEI 20 \/ PROJECTLAB Artisti &#038; Studenti dell\u2019Accademia di Belle Arti a Napoli\">&#8230; Read more &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2675,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[15],"class_list":["post-2666","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-museo-nitsch","cat_museo-nitsch"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA ROSA DEI 20 \/ PROJECTLAB Artisti &amp; Studenti dell\u2019Accademia di Belle Arti a Napoli - Fondazione Morra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA ROSA DEI 20 \/ PROJECTLAB Artisti &amp; Studenti dell\u2019Accademia di Belle Arti a Napoli - Fondazione Morra\" \/>\n<meta property=\"og:description\" content=\"24 novembre 2017 &#8211; 6 gennaio 2018 OPENING 24 NOVEMBRE ORE 19:00 Biblioteca del Museo Hermann Nitsch Vico Lungo Pontecorvo 29\/d, Napoli A cura di Guglielmo Gigliotti e Loredana Troise... Read more &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Morra\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-08T09:50:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/La_Rosa-dei-20_im-copertina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"942\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/\",\"name\":\"LA ROSA DEI 20 \\\/ PROJECTLAB Artisti & Studenti dell\u2019Accademia di Belle Arti a Napoli - Fondazione Morra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/La_Rosa-dei-20_im-copertina.jpg\",\"datePublished\":\"2020-11-17T11:12:05+00:00\",\"dateModified\":\"2021-04-08T09:50:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/La_Rosa-dei-20_im-copertina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/La_Rosa-dei-20_im-copertina.jpg\",\"width\":590,\"height\":942},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LA ROSA DEI 20 \\\/ PROJECTLAB Artisti &#038; Studenti dell\u2019Accademia di Belle Arti a Napoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"name\":\"Fondazione Morra\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\",\"name\":\"Fondazione Morra\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"width\":106,\"height\":114,\"caption\":\"Fondazione Morra\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA ROSA DEI 20 \/ PROJECTLAB Artisti & Studenti dell\u2019Accademia di Belle Arti a Napoli - Fondazione Morra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/","og_locale":"it_IT","og_type":"article","og_title":"LA ROSA DEI 20 \/ PROJECTLAB Artisti & Studenti dell\u2019Accademia di Belle Arti a Napoli - Fondazione Morra","og_description":"24 novembre 2017 &#8211; 6 gennaio 2018 OPENING 24 NOVEMBRE ORE 19:00 Biblioteca del Museo Hermann Nitsch Vico Lungo Pontecorvo 29\/d, Napoli A cura di Guglielmo Gigliotti e Loredana Troise... Read more &raquo;","og_url":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/","og_site_name":"Fondazione Morra","article_modified_time":"2021-04-08T09:50:40+00:00","og_image":[{"width":590,"height":942,"url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/La_Rosa-dei-20_im-copertina.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/","url":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/","name":"LA ROSA DEI 20 \/ PROJECTLAB Artisti & Studenti dell\u2019Accademia di Belle Arti a Napoli - Fondazione Morra","isPartOf":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/La_Rosa-dei-20_im-copertina.jpg","datePublished":"2020-11-17T11:12:05+00:00","dateModified":"2021-04-08T09:50:40+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/#primaryimage","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/La_Rosa-dei-20_im-copertina.jpg","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/La_Rosa-dei-20_im-copertina.jpg","width":590,"height":942},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/la-rosa-dei-20-projectlab-artisti-studenti-dellaccademia-di-belle-arti-a-napoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionemorra.org\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.fondazionemorra.org\/it\/eventi\/"},{"@type":"ListItem","position":3,"name":"LA ROSA DEI 20 \/ PROJECTLAB Artisti &#038; Studenti dell\u2019Accademia di Belle Arti a Napoli"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionemorra.org\/it\/#website","url":"https:\/\/www.fondazionemorra.org\/it\/","name":"Fondazione Morra","description":"","publisher":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionemorra.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fondazionemorra.org\/it\/#organization","name":"Fondazione Morra","url":"https:\/\/www.fondazionemorra.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","width":106,"height":114,"caption":"Fondazione Morra"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/2666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/2666\/revisions"}],"predecessor-version":[{"id":6141,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/2666\/revisions\/6141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media\/2675"}],"wp:attachment":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media?parent=2666"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tags?post=2666"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=2666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}