{"id":2825,"date":"2020-11-20T16:13:51","date_gmt":"2020-11-20T15:13:51","guid":{"rendered":"http:\/\/www.fondazionemorra.org\/?post_type=tribe_events&#038;p=2825"},"modified":"2020-11-20T16:13:51","modified_gmt":"2020-11-20T15:13:51","slug":"ekrem-yalcindag-the-language-of-diversity","status":"publish","type":"tribe_events","link":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/","title":{"rendered":"Ekrem Yalcindag &#8211; The Language of Diversity"},"content":{"rendered":"<p><strong>19 febbraio &#8211; 19 marzo 2016<\/strong><br \/>\nOPENING 19 FEBBRAIO ORE 18:30<br \/>\n<strong>Museo Hermann Nitsch\u00a0<\/strong><br \/>\nVico Lungo Pontecorvo 29\/d, Napoli<\/p>\n<p style=\"text-align: justify;\">Nelle sale della Biblioteca del Museo Nitsch, si \u00e8 tenuta la prima mostra in Italia dell\u2019artista turco Ekrem Yal\u00e7\u0131nda\u011f.<\/p>\n<p style=\"text-align: justify;\">Le diciotto opere diverse per forma e colore rappresentano ci\u00f2 che di pi\u00f9 avvicina la tradizione orientale a quell\u2019occidentale, non pura decorazione ma esplosione di colori ottenuta attraverso una minuziosa indagine del particolare.<\/p>\n<p style=\"text-align: justify;\">\u201c\u2026lui reclama il linguaggio della molteplicit\u00e0. sono sempre le particelle pi\u00f9 piccole che compone su superfici pittoriche spesso gigantesche. lui tratta questi elementi come se fossero delle molecole, degli atomi. crea delle strutture simili a strutture molecolari. comunque la sua opera ha molto a che fare con la costruzione di strutture che si intrecciano, che spesso attraversano la superficie enorme delle sue opere. ci fanno pensare in qualche modo a modelli fisici, quasi utopici del processo della creazione del mondo. si suggeriscono processi di fertilizzazione. si sa che ha studiato le forme di fiori e foglie e che queste esperienze si rispecchiano nell\u2019ordine dei suoi quadri. universi di colori formati da gradazioni sottili conferiscono alle superfici, da lui plasmate, un eccesso cromatico. visualizza il divenire della creazione e nonostante ci\u00f2, manca la dimensione spaziale della velocit\u00e0, del tempo e dello spreco di spazio. assolutamente positiva ritengo la vicinanza delle sue opere alla op-art. questi artisti avevano gli stessi suoi problemi con l\u2019espressione artistica non figurativa. creare dei cerchi concentrici rappresenta un problema archetipico per gli artisti. il bersaglio dell\u2019arciere dei ciechi monaci buddisti zen indica la strada anche a ekrem. pi\u00f9 volte abbiamo parlato di spazio, della riproduzione prospettica dello spazio tramite la pittura figurativa, che doveva essere superata a favore della pittura astratta e dello spazio reso non figurativo dai tappeti orientali e dagli ornamenti. penso che i dipinti di ekremy alcindag contengono questa forza. i suoi dipinti trasmettono qualcosa dell\u2019effetto di opere realizzate da pittori del liberty. la terza dimensione passa in secondo piano a favore di una quarta dimensione, oggettivamente non spiegabile\u201d<\/p>\n<p style=\"text-align: right;\">Hermann Nitsch, Prinzendorf, gennaio 2016<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2825 gallery-columns-1 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/20160219_195026\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195026.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-2828\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195026.jpg 800w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195026-300x169.jpg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195026-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2828'>\n\t\t\t\tInstallation View, The Language of Diversity, Museo Hermann Nitsch, Napoli 2016\nEkrem Yal\u00e7\u0131nda\u011f\nCourtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/20160219_195054_001\/'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195054_001.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-2830\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195054_001.jpg 360w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195054_001-169x300.jpg 169w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2830'>\n\t\t\t\tInstallation View, The Language of Diversity, Museo Hermann Nitsch, Napoli 2016 Ekrem Yal\u00e7\u0131nda\u011f Courtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/20160219_194638_002\/'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_194638_002.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-2832\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_194638_002.jpg 360w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_194638_002-169x300.jpg 169w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2832'>\n\t\t\t\tInstallation View, The Language of Diversity, Museo Hermann Nitsch, Napoli 2016 Ekrem Yal\u00e7\u0131nda\u011f Courtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/20160219_195501_001\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195501_001.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-2826\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195501_001.jpg 800w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195501_001-300x169.jpg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/20160219_195501_001-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2826'>\n\t\t\t\tInstallation View, The Language of Diversity, Museo Hermann Nitsch, Napoli 2016 Ekrem Yal\u00e7\u0131nda\u011f Courtesy Fondazione Morra\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>19 febbraio &#8211; 19 marzo 2016 OPENING 19 FEBBRAIO ORE 18:30 Museo Hermann Nitsch\u00a0 Vico Lungo Pontecorvo 29\/d, Napoli Nelle sale della Biblioteca del Museo Nitsch, si \u00e8 tenuta la<a class=\"excerpt-read-more\" href=\"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/\" title=\"ReadEkrem Yalcindag &#8211; The Language of Diversity\">&#8230; Read more &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2834,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[15],"class_list":["post-2825","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-museo-nitsch","cat_museo-nitsch"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ekrem Yalcindag - The Language of Diversity - Fondazione Morra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ekrem Yalcindag - The Language of Diversity - Fondazione Morra\" \/>\n<meta property=\"og:description\" content=\"19 febbraio &#8211; 19 marzo 2016 OPENING 19 FEBBRAIO ORE 18:30 Museo Hermann Nitsch\u00a0 Vico Lungo Pontecorvo 29\/d, Napoli Nelle sale della Biblioteca del Museo Nitsch, si \u00e8 tenuta la... Read more &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Morra\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/Opening_Ekrem_YalcA_ndag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/\",\"name\":\"Ekrem Yalcindag - The Language of Diversity - Fondazione Morra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Opening_Ekrem_YalcA_ndag.jpg\",\"datePublished\":\"2020-11-20T15:13:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Opening_Ekrem_YalcA_ndag.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Opening_Ekrem_YalcA_ndag.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/ekrem-yalcindag-the-language-of-diversity\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ekrem Yalcindag &#8211; The Language of Diversity\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"name\":\"Fondazione Morra\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\",\"name\":\"Fondazione Morra\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"width\":106,\"height\":114,\"caption\":\"Fondazione Morra\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ekrem Yalcindag - The Language of Diversity - Fondazione Morra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/","og_locale":"it_IT","og_type":"article","og_title":"Ekrem Yalcindag - The Language of Diversity - Fondazione Morra","og_description":"19 febbraio &#8211; 19 marzo 2016 OPENING 19 FEBBRAIO ORE 18:30 Museo Hermann Nitsch\u00a0 Vico Lungo Pontecorvo 29\/d, Napoli Nelle sale della Biblioteca del Museo Nitsch, si \u00e8 tenuta la... Read more &raquo;","og_url":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/","og_site_name":"Fondazione Morra","og_image":[{"width":800,"height":500,"url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/Opening_Ekrem_YalcA_ndag.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/","url":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/","name":"Ekrem Yalcindag - The Language of Diversity - Fondazione Morra","isPartOf":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/Opening_Ekrem_YalcA_ndag.jpg","datePublished":"2020-11-20T15:13:51+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/#primaryimage","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/Opening_Ekrem_YalcA_ndag.jpg","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2020\/11\/Opening_Ekrem_YalcA_ndag.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/ekrem-yalcindag-the-language-of-diversity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionemorra.org\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.fondazionemorra.org\/it\/eventi\/"},{"@type":"ListItem","position":3,"name":"Ekrem Yalcindag &#8211; The Language of Diversity"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionemorra.org\/it\/#website","url":"https:\/\/www.fondazionemorra.org\/it\/","name":"Fondazione Morra","description":"","publisher":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionemorra.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fondazionemorra.org\/it\/#organization","name":"Fondazione Morra","url":"https:\/\/www.fondazionemorra.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","width":106,"height":114,"caption":"Fondazione Morra"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/2825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/2825\/revisions"}],"predecessor-version":[{"id":2836,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/2825\/revisions\/2836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media\/2834"}],"wp:attachment":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media?parent=2825"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tags?post=2825"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=2825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}