{"id":6362,"date":"2021-05-20T15:04:45","date_gmt":"2021-05-20T13:04:45","guid":{"rendered":"http:\/\/www.fondazionemorra.org\/?post_type=tribe_events&#038;p=6362"},"modified":"2021-11-24T13:04:28","modified_gmt":"2021-11-24T12:04:28","slug":"the-art-of-remembering-residenza-dartista","status":"publish","type":"tribe_events","link":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/","title":{"rendered":"The art of remembering &#8211; Residenza d&#8217;artista"},"content":{"rendered":"<p><strong>CALL PER RESIDENZA D&#8217;ARTISTA<\/strong><br \/>\nIscrizioni aperte <strong>dal 20 maggio al 20 luglio 2021<\/strong><\/p>\n<p><strong>21 settembre &#8211; 5 ottobre 2021<br \/>\n<\/strong><strong>Museo Hermann Nitsch<br \/>\n<\/strong>Vico Lungo Pontecorvo 29\/d, Napoli<\/p>\n<p>La Fondazione Morra con il collettivo <em>The rabbit hole<\/em> e la E-M Arts associazione culturale presentano la residenza d\u2019artista <em>the art of remembering<\/em>.<\/p>\n<p>3 candidati residenti a Napoli o nei Comuni limitrofi potranno trascorrere, insieme ad altri 7 candidati internazionali, quattordici giorni nella residenza della Fondazione Morra ed al Museo Hermann Nitsch, nel cuore del Quartiere dell\u2019Arte di Napoli, per esplorare l\u2019<em>arte del ricordare<\/em>.<\/p>\n<p>Siamo particolarmente interessati alle persone con un vivo interesse per i viaggi, le escursioni, i porti e le vie di navigazione, cos\u00ec come per i simboli antichi, per le scritture e per i codici, che si possono veicolare attraverso la poesia, il teatro, le sonorit\u00e0, la matematica e la performance.<\/p>\n<p>Gli artisti avranno la possibilit\u00e0 di esplorare l\u2019argomento in maniera individuale, in un ambiente contemplativo e stimolante, ma anche di collaborare con gli altri candidati, favorendo un incontro di menti.<\/p>\n<p>Come segmento del programma, i candidati potranno conoscere la scena creativa di Napoli, incontrare alcuni artisti e personalit\u00e0 della citt\u00e0 ed immergersi nelle onde del mare e della cultura.<\/p>\n<p>Questo programma di residenza \u00e8 pensato come un\u2019indagine mistica, quindi invitiamo le menti curiose che hanno un particolare interesse per il sublime e per la scoperta di nuovi spazi di conoscenza, a catturare la misteriosa e magica piuma bianca e presentare la candidatura.<\/p>\n<p><strong>Metodologia<\/strong><\/p>\n<p>Ogni candidato interrogher\u00e0 il tema del \u201cricordare\u201d immergendosi in The Rabbit Hole Method\u2122, un processo di indagine che estrae e distilla dalle pratiche artistiche contemporanee, dalla filosofia, dal misticismo, dalla matematica e dalla danza. Il metodo include la lezione, tra gli altri, di Hazrat Inayat Khan, Farid Ud-Din Attar, Jorge Luis Borges, Alejandro Jodorowsky, Lewis Carroll. The Rabbit Hole cerca di stimolare nuove idee sul s\u00e9 e l\u2019altro, e di sfidare i limiti e i confini costruiti culturalmente.<\/p>\n<p>Sotto l\u2019attenta consulenza della Georgetown University e del MIT Senselab, il programma basa i propri principi sulla decostruzione e sulla reinvenzione dei rituali e delle strutture. Lavora, inoltre, con il <em>Teatro de los Sentidos<\/em> di Barcellona, una compagnia teatrale immersiva che crea esperienze decostruendo quella che \u00e8 diventata la nostra presunta mappatura sensoriale, e scopre il magico filo d\u2019argento che si mostra, se si \u00e8 aperti al ricordare.<\/p>\n<p><strong>Prospettive per i candidati-artisti<\/strong><\/p>\n<p>Ogni candidato dovr\u00e0 sviluppare in italiano o in inglese una risposta all\u2019<em>arte del ricordare<\/em> che verr\u00e0 successivamente presentata al Museo Hermann Nitsch.<\/p>\n<p>Ogni lavoro entrer\u00e0 a far parte di un archivio che riflette The Rabbit Hole Method\u2122.<\/p>\n<p>Un evento finale al termine della residenza inviter\u00e0 il pubblico a incontrare gli artisti, a introdurre la metodologia e a coinvolgere le comunit\u00e0 artistiche locali attraverso l\u2019immersione sensoriale e il gioco.<\/p>\n<p>A conclusione della residenza<\/p>\n<p>Ogni artista ricever\u00e0 un certificato master class del The Rabbit Hole Method\u2122<\/p>\n<p>Il lavoro di ogni artista verr\u00e0 promosso attraverso i canali global di The Rabbit Hole. Ogni artista avr\u00e0 un posto nel collettivo The Rabbit Hole.<\/p>\n<p><strong>Chi pu\u00f2 presentare domanda<\/strong><\/p>\n<p>Con la possibilit\u00e0 di offrire solo 3 posti per questa residenza, selezioneremo i candidati sia per il proprio merito artistico e la passione per la materia, che per il modo in cui ciascuno possa contribuire a una sinergia generale di gruppo.<\/p>\n<p>Artisti, curatori, scrittori, compositori, poeti, ricercatori, musicisti, performer, di ogni provenienza formativa sono invitati a presentare domanda.<\/p>\n<p>Per partecipare, inviare quanto segue a <a href=\"mailto:info@fondazionemorra.org\">info@fondazionemorra.org<\/a><\/p>\n<p>&#8211; una dichiarazione in italiano o in inglese sul progetto sul quale si desidera lavorare<\/p>\n<p>&#8211; una dichiarazione in italiano o in inglese in relazione all\u2019<em>arte del ricordare<\/em> (circa 400 parole)<\/p>\n<p>&#8211; una risposta in italiano o in inglese alla domanda che segue (circa 400 parole)<\/p>\n<p>&#8211; il tuo curriculum<\/p>\n<p>&#8211; il tuo sito web<\/p>\n<p><strong>Deadline 20 Luglio 2021<\/strong><\/p>\n<p><strong>La domanda<\/strong><\/p>\n<p>Leggi la seguente poesia e rispondi alla domanda<\/p>\n<p>\u201cCos&#8217;\u00e8 che ci collega<\/p>\n<p>Un ricordo?<\/p>\n<p>E se smettessimo di ricordare?\u201d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6363\" src=\"http:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/POEM.png\" alt=\"\" width=\"750\" height=\"735\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/POEM.png 750w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/POEM-300x294.png 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Fondato a New York nel 2008, il collettivo <strong>the rabbit hole<\/strong> &#8211; composto da un gruppo di artisti, scrittori e visionari irriverenti &#8211; conta oltre 2000 partecipanti in 56 paesi.<\/p>\n<p>Il collettivo vuole stimolare nuove idee su se stessi e sugli altri e sfidare i limiti e i confini costruiti culturalmente. Un manifesto, scritto dai suoi fondatori, basa i propri principi sulla decostruzione e sulla reinvenzione di rituali e strutture.<\/p>\n<p>Seguendo un fondamento della festosit\u00e0 e una celebrazione della perturbazione, the rabbit hole ha creato provocatorie mostre partecipative al Chelsea Art Museum, un autobus a due piani che viaggia nel tempo a New York City, un catamarano nel Mediterraneo e un viaggio in treno di 21 giorni attraverso l\u2019Europa e il Medio Oriente, tra gli altri luoghi.<\/p>\n<p><a href=\"http:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/the-rabbit-hole-CALL-NAPOLI.pdf\" target=\"_blank\" rel=\"noopener\">Comunicato stampa<\/a><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-6362 gallery-columns-1 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/attachment\/002\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1200\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/002.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-7128\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/002.jpg 800w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/002-200x300.jpg 200w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/002-683x1024.jpg 683w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/002-768x1152.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-7128'>\n\t\t\t\tLabyrinth of mirrors in The art of remembering, Napoli, 2021 \u00a9 photo Imma Di Lillo\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/attachment\/005\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"887\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/005.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-7130\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/005.jpg 1200w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/005-300x222.jpg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/005-1024x757.jpg 1024w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/005-768x568.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-7130'>\n\t\t\t\tThe art of evoking in The art of remembering, Museo Hermann Nitsch, Napoli, 2021 \u00a9 photo Imma Di Lillo\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/attachment\/001\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/001.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-7126\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/001.jpg 1200w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/001-300x200.jpg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/001-1024x683.jpg 1024w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/001-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-7126'>\n\t\t\t\tAlper Akcay, The Whirling Begins in The art of remembering, Museo Hermann Nitsch, Napoli, 2021 \u00a9 photo Sabrina Cirillo\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/attachment\/007\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/007.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-7132\" srcset=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/007.jpeg 1200w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/007-300x225.jpeg 300w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/007-1024x768.jpeg 1024w, https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/007-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-7132'>\n\t\t\t\tBody, Time, Space, Access in The art of remembering, Museo Hermann Nitsch, Napoli, 2021 \u00a9 photo Samina Virani\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>CALL PER RESIDENZA D&#8217;ARTISTA Iscrizioni aperte dal 20 maggio al 20 luglio 2021 21 settembre &#8211; 5 ottobre 2021 Museo Hermann Nitsch Vico Lungo Pontecorvo 29\/d, Napoli La Fondazione Morra<a class=\"excerpt-read-more\" href=\"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/\" title=\"ReadThe art of remembering &#8211; Residenza d&#8217;artista\">&#8230; Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":6394,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[15],"class_list":["post-6362","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-museo-nitsch","cat_museo-nitsch"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The art of remembering - Residenza d&#039;artista - Fondazione Morra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The art of remembering - Residenza d&#039;artista - Fondazione Morra\" \/>\n<meta property=\"og:description\" content=\"CALL PER RESIDENZA D&#8217;ARTISTA Iscrizioni aperte dal 20 maggio al 20 luglio 2021 21 settembre &#8211; 5 ottobre 2021 Museo Hermann Nitsch Vico Lungo Pontecorvo 29\/d, Napoli La Fondazione Morra... Read more &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Morra\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-24T12:04:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/image0.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/\",\"name\":\"The art of remembering - Residenza d'artista - Fondazione Morra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/image0.jpeg\",\"datePublished\":\"2021-05-20T13:04:45+00:00\",\"dateModified\":\"2021-11-24T12:04:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/image0.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/image0.jpeg\",\"width\":775,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/evento\\\/the-art-of-remembering-residenza-dartista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The art of remembering &#8211; Residenza d&#8217;artista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"name\":\"Fondazione Morra\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#organization\",\"name\":\"Fondazione Morra\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazionemorra.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.png\",\"width\":106,\"height\":114,\"caption\":\"Fondazione Morra\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionemorra.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The art of remembering - Residenza d'artista - Fondazione Morra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/","og_locale":"it_IT","og_type":"article","og_title":"The art of remembering - Residenza d'artista - Fondazione Morra","og_description":"CALL PER RESIDENZA D&#8217;ARTISTA Iscrizioni aperte dal 20 maggio al 20 luglio 2021 21 settembre &#8211; 5 ottobre 2021 Museo Hermann Nitsch Vico Lungo Pontecorvo 29\/d, Napoli La Fondazione Morra... Read more &raquo;","og_url":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/","og_site_name":"Fondazione Morra","article_modified_time":"2021-11-24T12:04:28+00:00","og_image":[{"width":775,"height":1200,"url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/image0.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/","url":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/","name":"The art of remembering - Residenza d'artista - Fondazione Morra","isPartOf":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/image0.jpeg","datePublished":"2021-05-20T13:04:45+00:00","dateModified":"2021-11-24T12:04:28+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/#primaryimage","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/image0.jpeg","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/05\/image0.jpeg","width":775,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionemorra.org\/it\/evento\/the-art-of-remembering-residenza-dartista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionemorra.org\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.fondazionemorra.org\/it\/eventi\/"},{"@type":"ListItem","position":3,"name":"The art of remembering &#8211; Residenza d&#8217;artista"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionemorra.org\/it\/#website","url":"https:\/\/www.fondazionemorra.org\/it\/","name":"Fondazione Morra","description":"","publisher":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionemorra.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fondazionemorra.org\/it\/#organization","name":"Fondazione Morra","url":"https:\/\/www.fondazionemorra.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","contentUrl":"https:\/\/www.fondazionemorra.org\/wp-content\/uploads\/2021\/02\/logo.png","width":106,"height":114,"caption":"Fondazione Morra"},"image":{"@id":"https:\/\/www.fondazionemorra.org\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/6362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":5,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/6362\/revisions"}],"predecessor-version":[{"id":7134,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events\/6362\/revisions\/7134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media\/6394"}],"wp:attachment":[{"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/media?parent=6362"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tags?post=6362"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.fondazionemorra.org\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=6362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}